{"id":75083,"date":"2022-09-08T18:28:20","date_gmt":"2022-09-08T18:28:20","guid":{"rendered":"https:\/\/www.dimecuba.com\/revista\/?p=75083"},"modified":"2023-03-11T23:07:23","modified_gmt":"2023-03-11T23:07:23","slug":"biografia-ivan-pedroso","status":"publish","type":"post","link":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/","title":{"rendered":"Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y forjador de campeones"},"content":{"rendered":"<p>A trav\u00e9s de esta breve biograf\u00eda conoce m\u00e1s acerca de Iv\u00e1n Pedroso, exatleta cubano y uno de los m\u00e1s respetables entrenadores en triple salto.<\/p>\n<h2>\u00bfQui\u00e9n es Iv\u00e1n Pedroso?<\/h2>\n<p>Iv\u00e1n Pedroso es un exatleta ol\u00edmpico cubano de 49 a\u00f1os, especializado sobre todo en la categor\u00eda de triple salto. Adem\u00e1s, tras su retiro en la pr\u00e1ctica de este deporte, se convirti\u00f3 en el entrenador de cinco atletas ganadores de medallas de talla mundial; entre ellos Yulimar Rojas (r\u00e9cord ol\u00edmpico).<\/p>\n<h3>\u00bfD\u00f3nde naci\u00f3 Iv\u00e1n Pedroso?<\/h3>\n<p>Como todas las biograf\u00edas que les hemos compartido, la de Iv\u00e1n Pedroso inicia ofreciendo datos importantes acerca de su nacimiento. En primer lugar, destacaremos que su nombre completo es Iv\u00e1n L\u00e1zaro Pedroso Soler, y naci\u00f3 el 17 de diciembre de 1972 en la ciudad de La Habana.<\/p>\n<h3>\u00bfD\u00f3nde vive actualmente Iv\u00e1n Pedroso?<\/h3>\n<p>Aunque, actualmente, Iv\u00e1n Pedroso es una de las m\u00e1s grandes glorias deportivas de Cuba en el atletismo, ahora mismo se encuentra lejos de casa. Por lo tanto, hoy vive en Guadalajara, Espa\u00f1a donde se desempe\u00f1a como entrenador de talentosos atletas de talla internacional; obteniendo importantes logros.<\/p>\n<p>Como resultado, desde la naci\u00f3n ib\u00e9rica ha asumido el entrenamiento de atletas en triple salto, quienes con su ayuda se han convertido en destacados medallistas. Entre ellos, tenemos a Teddy Tamgho, la venezolana y r\u00e9cord mundial ol\u00edmpico Yulimar Rojas, Ana Peleteiro, Nelson \u00c9vora y el tambi\u00e9n cubano Jordan D\u00edaz (r\u00e9cord espa\u00f1ol).<\/p>\n<h2>Carrera deportiva<\/h2>\n<p>Sin duda, la biograf\u00eda de Iv\u00e1n Pedroso est\u00e1 marcada por importantes logros a lo largo de su trayectoria como deportista cubano. Desde muy peque\u00f1o, Pedroso mostr\u00f3 inter\u00e9s por la ejecuci\u00f3n de saltos, involucr\u00e1ndose desde la adolescencia en el atletismo.<\/p>\n<p>Por lo tanto, siendo a\u00fan muy joven, participa en pruebas de medio fondo; hasta que el entrenador Mil\u00e1n Matos lo prepara para el salto de longitud. Esta decisi\u00f3n sorprendi\u00f3 a muchos, considerando que con una estatura de 1,77 metros Pedroso estaba por debajo del promedio que practica esta disciplina atl\u00e9tica.<\/p>\n<p>Pese a ello, Iv\u00e1n Pedroso no defraud\u00f3 a su entrenador ni a su pa\u00eds, y se desarroll\u00f3 satisfactoriamente. En consecuencia, teniendo menos de 13 a\u00f1os consigui\u00f3 representar a Cuba en los Juegos Panamericanos de La Habana en 1991.<\/p>\n<p>Seguidamente, el atleta que pronto se dio a conocer como \u201cel terrible Pedroso\u201d acudi\u00f3 a sus primeros Juegos Ol\u00edmpicos, en Barcelona 92. All\u00ed, dej\u00f3 a muchos at\u00f3nitos al conseguir un fabuloso cuarto lugar; lo que lo motiv\u00f3 a seguir esforz\u00e1ndose e ir por m\u00e1s.<\/p>\n<p>Durante los a\u00f1os sucesivos, el tambi\u00e9n llamado saltamontes de Cuba participa en varios cert\u00e1menes de atletismo internacionales.<\/p>\n<p>Como resultado, consigui\u00f3 llevarse a casa varias medallas de oro en pa\u00edses como Canad\u00e1 (1993), Espa\u00f1a (1995) y Argentina (1995). En los mencionados eventos, Iv\u00e1n Pedroso obtuvo excelentes resultados, con marcas de 8.23m; 8.51m y 8.50m; respectivamente.<\/p>\n<p>Finalmente, la trayectoria deportiva de Iv\u00e1n Pedroso concluye en 2007 cuenta con nueve t\u00edtulos de campe\u00f3n mundial. Igualmente, es ganador de una medalla de oro ol\u00edmpico, en la prueba de salto largo, de S\u00eddney (2000).<\/p>\n<p>Tambi\u00e9n, tiene cuatro medallas de oro en campeonatos mundiales de atletismo y cinco preseas doradas en iguales competiciones, bajo techo. En los Juegos Panamericanos gan\u00f3 tres medallas de oros y una medalla de plata.<\/p>\n<h3><span id=\"Cual_es_la_mejor_marca_de_Ivan_Pedroso\">\u00bfCu\u00e1l es la mejor marca de Iv\u00e1n Pedroso?<\/span><\/h3>\n<p>Aunque Iv\u00e1n Pedroso tiene en su haber m\u00e1s de 19 medallas de oro en eventos internacionales, sin duda, hay una que goza de gran relevancia. Esto, debido a que junto a la medalla consigui\u00f3 lo que viene siendo la mejor marca de su trayectoria como atleta especializado en triple salto.<\/p>\n<p>Por lo tanto, la mejor marca en triple salto de Iv\u00e1n Pedroso, la obtuvo en Suecia, donde con 16 a\u00f1os logr\u00f3 un salto de 8.70 metros. Este importante logro lo realiz\u00f3 en el a\u00f1o 1995, durante las competencias del Campeonato Mundial de Atletismo en Gotemburgo.<\/p>\n<p>Seguidamente, el mejor n\u00famero del terrible Pedroso lo obtuvo en Jap\u00f3n, durante el Campeonato Mundial bajo techo 1999. Entonces, ejecut\u00f3 un salto de 8.62 metros que le permiti\u00f3 llevarse la medalla de oro a casa.<\/p>\n<p>Ese mismo a\u00f1o, con un salto de 8.56m gana el oro en el Campeonato Mundial de Atletismo en Espa\u00f1a. Mientras que, en el a\u00f1o 2000 obtiene la medalla de oro en los Juegos Ol\u00edmpicos realizados en S\u00eddney.<\/p>\n<p>Asimismo, Iv\u00e1n Pedroso tiene un gran palmar\u00e9s obtenido en importantes competiciones internacionales. <strong><a href=\"https:\/\/www.ecured.cu\/Iv%C3%A1n_Pedroso#Palmar.C3.A9s\" target=\"_blank\" rel=\"noopener\">Consulta todos los resultados aqu\u00ed.<\/a><\/strong><\/p>\n<h2>Ivan Pedroso como entrenador: \u00bfA qui\u00e9nes entrena?<\/h2>\n<p>Tal como mencionamos antes, la carrera de Iv\u00e1n Pedroso como atleta concluy\u00f3 en 2007, pero seguidamente se inici\u00f3 como entrenador. Por lo tanto, al retirarse del deporte, se dedic\u00f3 al entrenamiento en salto en la ciudad espa\u00f1ola de Guadalajara, trabajando con atletas de todo el mundo.<\/p>\n<p>Asimismo, varios de sus pupilos han logrado importantes triunfos deportivos desde que est\u00e1n en sus manos. Como resultado, varios de ellos se han convertido en grandes glorias del atletismo, siguiendo las huellas de tan loable mentor.<\/p>\n<h3>1. Yulimar Rojas<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-75086 size-large\" title=\"Iv\u00e1n Pedroso es el entrenador de Yulimar Rojas\" src=\"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2022\/03\/entrenador-ivan-pedroso-yulimar-rojas-1024x536.png\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/entrenador-ivan-pedroso-yulimar-rojas-150x79.png?lossy=1&amp;strip=1&amp;webp=1 150w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/entrenador-ivan-pedroso-yulimar-rojas-300x157.png?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/entrenador-ivan-pedroso-yulimar-rojas-390x205.png?lossy=1&amp;strip=1&amp;webp=1 390w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/entrenador-ivan-pedroso-yulimar-rojas.png?size=480x251&amp;lossy=1&amp;strip=1&amp;webp=1 480w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/entrenador-ivan-pedroso-yulimar-rojas.png?size=640x335&amp;lossy=1&amp;strip=1&amp;webp=1 640w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/entrenador-ivan-pedroso-yulimar-rojas-768x402.png?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/entrenador-ivan-pedroso-yulimar-rojas-1024x536.png?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/entrenador-ivan-pedroso-yulimar-rojas.png?lossy=1&amp;strip=1&amp;webp=1 1280w\" alt=\"Iv\u00e1n Pedroso es el entrenador de Yulimar Rojas\" width=\"800\" height=\"419\" \/><\/p>\n<p>En 2016, la venezolana <a href=\"https:\/\/es.wikipedia.org\/wiki\/Yulimar_Rojas\">Yulimar Rojas<\/a> gan\u00f3 la medalla de plata ol\u00edmpica, de R\u00edo de Janeiro. Luego, la atleta gan\u00f3 la medalla de oro, en la disciplina de salto triple, en las olimpiadas de Tokio, en 2020, donde bati\u00f3 el r\u00e9cord mundial con un salto de 15.67 metros.<\/p>\n<p>En 2022, Yulimar Rojas bati\u00f3 el r\u00e9cord del mundo en triple salto (con 15.74 metros) durante el Campeonato de Atletismo Bajo Techo, en Belgrado.<\/p>\n<p>La pupila de Ivan Pedroso se convirti\u00f3 as\u00ed en 3 veces campeona del oro mundial de triple salto.<\/p>\n<p>En 2020, <a href=\"https:\/\/es.wikipedia.org\/wiki\/Ana_Peleteiro\">Ana Peleteiro<\/a> consigui\u00f3 la medalla de bronce en los Juegos Ol\u00edmpicos de Tokio.\u00a0La espa\u00f1ola, de 25 a\u00f1os, afirma que Iv\u00e1n fue su salvaci\u00f3n como atleta:<\/p>\n<p>\u00abIv\u00e1n ha sido la persona que ha confiado en m\u00ed, que me ha sacado de la mierda absoluta, de una ni\u00f1a que pesaba 65 kilos, que le sobraba grasa por todos lados, un talento que estaba roto. Era un juguete roto, literalmente. Confi\u00f3 en m\u00ed, me agarr\u00f3 y me dijo: Lo vamos a hacer. No s\u00e9 si ser\u00e1 aqu\u00ed, en cinco o diez a\u00f1os, no s\u00e9 cu\u00e1ndo ser\u00e1, pero vamos a hacer algo grande juntos\u00bb.<\/p>\n<h3>3. Jordan D\u00edaz<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-75090 size-large\" title=\"Iv\u00e1n Pedroso es el entrenador de Jordan D\u00edaz\" src=\"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2022\/03\/jordan-diaz-1024x536.png\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/jordan-diaz-150x79.png?lossy=1&amp;strip=1&amp;webp=1 150w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/jordan-diaz-300x157.png?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/jordan-diaz-390x205.png?lossy=1&amp;strip=1&amp;webp=1 390w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/jordan-diaz.png?size=480x251&amp;lossy=1&amp;strip=1&amp;webp=1 480w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/jordan-diaz.png?size=640x335&amp;lossy=1&amp;strip=1&amp;webp=1 640w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/jordan-diaz-768x402.png?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/jordan-diaz-1024x536.png?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/jordan-diaz.png?lossy=1&amp;strip=1&amp;webp=1 1280w\" alt=\"Iv\u00e1n Pedroso es el entrenador de Jordan D\u00edaz\" width=\"800\" height=\"419\" \/><\/p>\n<p>El atleta cubano Jordan D\u00edaz <a href=\"https:\/\/www.dimecuba.com\/revista\/noticias-cuba\/cubano-record-salto-espana\/\">bati\u00f3 el r\u00e9cord en la categor\u00eda de triple salto<\/a>, en Espa\u00f1a, convirti\u00e9ndose en l\u00edder mundial del 2022.<\/p>\n<p>El joven atleta cubano se coron\u00f3 con el oro al participar en el Campeonato sub-23 de atletismo de Espa\u00f1a; tras romper una extraordinaria marca en salto. Alcanz\u00f3 los 17.27 metros al efectuar un magn\u00edfico e impecable triple salto.<\/p>\n<h3>4. Teddy Tamgho<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-75089 size-large\" src=\"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2022\/03\/ivan-pedroso-Teddy-Tamgho-1024x536.png\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/ivan-pedroso-Teddy-Tamgho-150x79.png?lossy=1&amp;strip=1&amp;webp=1 150w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/ivan-pedroso-Teddy-Tamgho-300x157.png?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/ivan-pedroso-Teddy-Tamgho-390x205.png?lossy=1&amp;strip=1&amp;webp=1 390w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/ivan-pedroso-Teddy-Tamgho.png?size=480x251&amp;lossy=1&amp;strip=1&amp;webp=1 480w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/ivan-pedroso-Teddy-Tamgho.png?size=640x335&amp;lossy=1&amp;strip=1&amp;webp=1 640w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/ivan-pedroso-Teddy-Tamgho-768x402.png?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/ivan-pedroso-Teddy-Tamgho-1024x536.png?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b1716519.smushcdn.com\/1716519\/wp-content\/uploads\/2022\/03\/ivan-pedroso-Teddy-Tamgho.png?lossy=1&amp;strip=1&amp;webp=1 1280w\" alt=\"\" width=\"800\" height=\"419\" \/><\/p>\n<p>Iv\u00e1n Pedroso entren\u00f3 a <a href=\"https:\/\/es.wikipedia.org\/wiki\/Teddy_Tamgho\">Teddy Tamgho<\/a>, un franc\u00e9s que gan\u00f3 una medalla de oro en el Campeonato Mundial de Atletismo, en 2013.<\/p>\n<p>El atleta, de 32 a\u00f1os,\u00a0bati\u00f3 3 r\u00e9cords mundiales de triple salto: 17.90 metros en Catar (2010), 17.91 en Par\u00eds (2011) y 17.92 metros en el Campeonato Europeo de Atletismo.<\/p>\n<h3>5. El portugu\u00e9s Nelson \u00c9vora<\/h3>\n<p>Por \u00faltimo, Iv\u00e1n fue el entrenador de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Nelson_%C3%89vora\">Nelson \u00c9vora<\/a>, quien fuera campe\u00f3n ol\u00edmpico de triple salto en Pek\u00edn, en 2008, y campe\u00f3n mundial en Osaka, en 2007.<\/p>\n<h2>Patrimonio de Iv\u00e1n Pedroso<\/h2>\n<p>Como resultado del arduo trabajo de Iv\u00e1n Pedroso como entrenador, este ha podido amasar un muy buen patrimonio en Espa\u00f1a. Aunque, hasta el momento, se desconoce una cifra exacta se estima que el patrimonio de este extraordinario deportista cubano est\u00e1 alrededor de los 11 millones de d\u00f3lares.<\/p>\n<p>Asimismo, dicha cifra continuar\u00eda en ascenso, gracias al alto rendimiento y efectividad alcanzada con los j\u00f3venes atletas que hoy est\u00e1n en sus manos. Por ejemplo, actualmente Espa\u00f1a le est\u00e1 pagando a Iv\u00e1n Pedroso por preparar a su compatriota Jordan D\u00edaz, rumbo a las Olimpiadas de Par\u00eds 2024.<\/p>\n<h2>Palabras Finales<\/h2>\n<p>Sin duda, Iv\u00e1n Pedroso es un admirable ejemplo para todos los cubanos gracias a sus grandes logros como deportista, y ahora como entrenador. Su perseverancia le ha permitido obtener reconocimiento internacional, as\u00ed como el respeto y admiraci\u00f3n de muchos.<\/p>\n<p>A pesar de que su carrera deportiva lleg\u00f3 a su fin, este decidi\u00f3 continuar dejando huella como atleta formando a otros j\u00f3venes en el salto. Como resultado, su legado se ha inmortalizado y sigue creciendo a trav\u00e9s del triunfo de otros atletas como Yulimar Rojas, y j\u00f3venes promesas como Jordan D\u00edaz.<\/p>\n<p><strong>Recomendados:\u00a0<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.dimecuba.com\/revista\/cubanos\/mejores-deportistas-cubanos\/\" target=\"_blank\" rel=\"noopener\">Los 15 mejores deportistas cubanos de todos los tiempos<\/a><\/li>\n<li><a href=\"https:\/\/www.dimecuba.com\/revista\/cubanos\/boxeadores-cubanos-profesionales-en-estados-unidos\/\" target=\"_blank\" rel=\"noopener\">Los 10 boxeadores cubanos profesionales en Estados Unidos m\u00e1s exitosos<\/a><\/li>\n<li><a href=\"https:\/\/www.dimecuba.com\/revista\/cubanos\/peloteros-cubanos-grandes-ligas\/\" target=\"_blank\" rel=\"noopener\">Top 10 peloteros cubanos en Grandes Ligas m\u00e1s exitosos y mejor pagados 2022<\/a><\/li>\n<li><a href=\"https:\/\/www.dimecuba.com\/revista\/cubanos\/mejores-boxeadores-cubanos\/\" target=\"_blank\" rel=\"noopener\">Los 15 mejores boxeadores cubanos de todos los tiempos<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Iv\u00e1n Pedroso es un destacado exatleta cubano, ganador de numerosos premios mundiales, y uno de los m\u00e1s respetados entrenadores<\/p>\n","protected":false},"author":13,"featured_media":75087,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[4032],"tags":[1096],"class_list":["post-75083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cubanos","tag-deporte-cubano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y entrenador<\/title>\n<meta name=\"description\" content=\"Conoce con esta briograf\u00eda m\u00e1s acerca de Iv\u00e1n Pedroso, multicampe\u00f3n cubano y actualmente de los mejores entrenadores en triple salto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y forjador de campeones\" \/>\n<meta property=\"og:description\" content=\"Iv\u00e1n Pedroso, de 49 a\u00f1os, es un entrenador cubano de triple salto que se ha encargado del entrenamiento de 5 medallistas de talla mundial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista DimeCuba\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/DimeCuba\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-08T18:28:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-11T23:07:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2022\/03\/ivan-pedroso-entrenador.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Iv\u00e1n Pedroso, de 49 a\u00f1os, es un entrenador cubano de triple salto que se ha encargado del entrenamiento de 5 medallistas de talla mundial.\" \/>\n<meta name=\"twitter:creator\" content=\"@dimecuba\" \/>\n<meta name=\"twitter:site\" content=\"@dimecuba\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#\\\/schema\\\/person\\\/a95cec0041795e625b7a764faccf8c52\"},\"headline\":\"Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y forjador de campeones\",\"datePublished\":\"2022-09-08T18:28:20+00:00\",\"dateModified\":\"2023-03-11T23:07:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/\"},\"wordCount\":1484,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ivan-pedroso-entrenador.png\",\"keywords\":[\"Deporte cubano\"],\"articleSection\":[\"CUBANOS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/\",\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/\",\"name\":\"Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y entrenador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ivan-pedroso-entrenador.png\",\"datePublished\":\"2022-09-08T18:28:20+00:00\",\"dateModified\":\"2023-03-11T23:07:23+00:00\",\"description\":\"Conoce con esta briograf\u00eda m\u00e1s acerca de Iv\u00e1n Pedroso, multicampe\u00f3n cubano y actualmente de los mejores entrenadores en triple salto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ivan-pedroso-entrenador.png\",\"contentUrl\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ivan-pedroso-entrenador.png\",\"width\":1280,\"height\":670,\"caption\":\"Iv\u00e1n Pedroso: el entrenador cubano que fabrica medallistas de ORO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/biografia-ivan-pedroso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias de Cuba\",\"item\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CUBANOS\",\"item\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/cubanos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y forjador de campeones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/\",\"name\":\"Revista DimeCuba\",\"description\":\"\u00daltimas noticias y sucesos de Cuba\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#organization\",\"name\":\"DimeCuba\",\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Revista-DimeCuba-logo-sml-3.png\",\"contentUrl\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Revista-DimeCuba-logo-sml-3.png\",\"width\":201,\"height\":57,\"caption\":\"DimeCuba\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/DimeCuba\\\/\",\"https:\\\/\\\/x.com\\\/dimecuba\",\"https:\\\/\\\/www.instagram.com\\\/dimecuba\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dimecuba\",\"https:\\\/\\\/www.youtube.com\\\/dimecubaweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#\\\/schema\\\/person\\\/a95cec0041795e625b7a764faccf8c52\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/129d2b0487c25b1eec40b85bd0426a1b949ad13e3ea21697124b5c81cf8053db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/129d2b0487c25b1eec40b85bd0426a1b949ad13e3ea21697124b5c81cf8053db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/129d2b0487c25b1eec40b85bd0426a1b949ad13e3ea21697124b5c81cf8053db?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/author\\\/redacciondc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y entrenador","description":"Conoce con esta briograf\u00eda m\u00e1s acerca de Iv\u00e1n Pedroso, multicampe\u00f3n cubano y actualmente de los mejores entrenadores en triple salto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/","og_locale":"es_ES","og_type":"article","og_title":"Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y forjador de campeones","og_description":"Iv\u00e1n Pedroso, de 49 a\u00f1os, es un entrenador cubano de triple salto que se ha encargado del entrenamiento de 5 medallistas de talla mundial.","og_url":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/","og_site_name":"Revista DimeCuba","article_publisher":"https:\/\/facebook.com\/DimeCuba\/","article_published_time":"2022-09-08T18:28:20+00:00","article_modified_time":"2023-03-11T23:07:23+00:00","og_image":[{"width":1280,"height":670,"url":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2022\/03\/ivan-pedroso-entrenador.png","type":"image\/png"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_description":"Iv\u00e1n Pedroso, de 49 a\u00f1os, es un entrenador cubano de triple salto que se ha encargado del entrenamiento de 5 medallistas de talla mundial.","twitter_creator":"@dimecuba","twitter_site":"@dimecuba","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/#article","isPartOf":{"@id":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/www.dimecuba.com\/revista\/#\/schema\/person\/a95cec0041795e625b7a764faccf8c52"},"headline":"Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y forjador de campeones","datePublished":"2022-09-08T18:28:20+00:00","dateModified":"2023-03-11T23:07:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/"},"wordCount":1484,"commentCount":0,"publisher":{"@id":"https:\/\/www.dimecuba.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2022\/03\/ivan-pedroso-entrenador.png","keywords":["Deporte cubano"],"articleSection":["CUBANOS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/","url":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/","name":"Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y entrenador","isPartOf":{"@id":"https:\/\/www.dimecuba.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/#primaryimage"},"image":{"@id":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2022\/03\/ivan-pedroso-entrenador.png","datePublished":"2022-09-08T18:28:20+00:00","dateModified":"2023-03-11T23:07:23+00:00","description":"Conoce con esta briograf\u00eda m\u00e1s acerca de Iv\u00e1n Pedroso, multicampe\u00f3n cubano y actualmente de los mejores entrenadores en triple salto.","breadcrumb":{"@id":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/#primaryimage","url":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2022\/03\/ivan-pedroso-entrenador.png","contentUrl":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2022\/03\/ivan-pedroso-entrenador.png","width":1280,"height":670,"caption":"Iv\u00e1n Pedroso: el entrenador cubano que fabrica medallistas de ORO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dimecuba.com\/revista\/cubanos\/biografia-ivan-pedroso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias de Cuba","item":"https:\/\/www.dimecuba.com\/revista\/"},{"@type":"ListItem","position":2,"name":"CUBANOS","item":"https:\/\/www.dimecuba.com\/revista\/cubanos\/"},{"@type":"ListItem","position":3,"name":"Biograf\u00eda de Iv\u00e1n Pedroso: Todo sobre este campe\u00f3n y forjador de campeones"}]},{"@type":"WebSite","@id":"https:\/\/www.dimecuba.com\/revista\/#website","url":"https:\/\/www.dimecuba.com\/revista\/","name":"Revista DimeCuba","description":"\u00daltimas noticias y sucesos de Cuba","publisher":{"@id":"https:\/\/www.dimecuba.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dimecuba.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.dimecuba.com\/revista\/#organization","name":"DimeCuba","url":"https:\/\/www.dimecuba.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.dimecuba.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2018\/10\/Revista-DimeCuba-logo-sml-3.png","contentUrl":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2018\/10\/Revista-DimeCuba-logo-sml-3.png","width":201,"height":57,"caption":"DimeCuba"},"image":{"@id":"https:\/\/www.dimecuba.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/DimeCuba\/","https:\/\/x.com\/dimecuba","https:\/\/www.instagram.com\/dimecuba\/","https:\/\/www.linkedin.com\/company\/dimecuba","https:\/\/www.youtube.com\/dimecubaweb"]},{"@type":"Person","@id":"https:\/\/www.dimecuba.com\/revista\/#\/schema\/person\/a95cec0041795e625b7a764faccf8c52","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/129d2b0487c25b1eec40b85bd0426a1b949ad13e3ea21697124b5c81cf8053db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/129d2b0487c25b1eec40b85bd0426a1b949ad13e3ea21697124b5c81cf8053db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/129d2b0487c25b1eec40b85bd0426a1b949ad13e3ea21697124b5c81cf8053db?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/www.dimecuba.com\/revista\/author\/redacciondc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/posts\/75083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/comments?post=75083"}],"version-history":[{"count":0,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/posts\/75083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/media\/75087"}],"wp:attachment":[{"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/media?parent=75083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/categories?post=75083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/tags?post=75083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}