{"id":90486,"date":"2024-08-20T15:34:47","date_gmt":"2024-08-20T15:34:47","guid":{"rendered":"https:\/\/www.dimecuba.com\/revista\/?p=90486"},"modified":"2024-08-26T15:57:54","modified_gmt":"2024-08-26T15:57:54","slug":"cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos","status":"publish","type":"post","link":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/","title":{"rendered":"Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos"},"content":{"rendered":"<p><span data-contrast=\"auto\">Lea Gallo se ha hecho viral en redes sociales, despu\u00e9s de que compartiera con miles de usuarios algunos \u201csecretos\u201d de su vida en el Army de Estados Unidos.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Oriunda de Santa Clara, esta cubana comparte a trav\u00e9s de su cuenta de TikTok, lo que come un soldado del ej\u00e9rcito americano en un d\u00eda de entrenamiento, as\u00ed como facetas m\u00e1s desconocidas de la armada.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Su manera espont\u00e1nea de contar su rutina muestra esa cara m\u00e1s humana de los integrantes del ej\u00e9rcito. Con sus videos tambi\u00e9n ha logrado que muchos internautas se interesen en pertenecer a las filas del Army, y as\u00ed se evidencia en muchos de los comentarios de sus publicaciones, donde le piden consejo y asesor\u00eda.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Entre los clips con m\u00e1s reproducciones de su cuenta en TikTok, destaca uno en el que prepara un delicioso caf\u00e9 al estilo m\u00e1s cubano, utilizando una cafetera italiana y el reconocido caf\u00e9 Bustelo, uno de los m\u00e1s consumido dentro de la comunidad latina en Estados Unidos.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\"> \u00a0<\/span><\/p>\n<blockquote class=\"tiktok-embed\" style=\"max-width: 605px; min-width: 325px;\" cite=\"https:\/\/www.tiktok.com\/@leagallo_\/video\/7394144827299958046\" data-video-id=\"7394144827299958046\">\n<section><a title=\"@leagallo_\" href=\"https:\/\/www.tiktok.com\/@leagallo_?refer=embed\" target=\"_blank\" rel=\"noopener\">@leagallo_<\/a> Buen comienzo del dia con cafe cubano! <a title=\"militares\" href=\"https:\/\/www.tiktok.com\/tag\/militares?refer=embed\" target=\"_blank\" rel=\"noopener\">#militares<\/a> <a title=\"armylifestyle\" href=\"https:\/\/www.tiktok.com\/tag\/armylifestyle?refer=embed\" target=\"_blank\" rel=\"noopener\">#armylifestyle<\/a> <a title=\"soldierlife\" href=\"https:\/\/www.tiktok.com\/tag\/soldierlife?refer=embed\" target=\"_blank\" rel=\"noopener\">#soldierlife<\/a> <a title=\"cuban\" href=\"https:\/\/www.tiktok.com\/tag\/cuban?refer=embed\" target=\"_blank\" rel=\"noopener\">#cuban<\/a> <a title=\"cubancoffee\" href=\"https:\/\/www.tiktok.com\/tag\/cubancoffee?refer=embed\" target=\"_blank\" rel=\"noopener\">#cubancoffee<\/a> <a title=\"ejercito\" href=\"https:\/\/www.tiktok.com\/tag\/ejercito?refer=embed\" target=\"_blank\" rel=\"noopener\">#ejercito<\/a> <a title=\"\u266c misses - Dominic Fike\" href=\"https:\/\/www.tiktok.com\/music\/misses-7364779997713074192?refer=embed\" target=\"_blank\" rel=\"noopener\">\u266c misses &#8211; Dominic Fike<\/a><\/section>\n<\/blockquote>\n<p><script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script><\/p>\n<p><span data-contrast=\"auto\">Los comentarios a estas im\u00e1genes remarcan el agradecimiento de muchos compatriotas por poner en alto a su pa\u00eds, siguiendo sus tradiciones a pesar de que vive desde hace muchos a\u00f1os en Miami.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">As\u00ed mismo, la antillana comparte tambi\u00e9n lo que suelen comer cuando est\u00e1n de maniobras, mostrando a su p\u00fablico un kit que consta de un paquete de macarrones con salsa de tomate, pretzel, prote\u00edna de chocolate, salsa de manzana y fresas, mantequilla de man\u00ed y galletitas.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\"> \u00a0<\/span><\/p>\n<blockquote class=\"tiktok-embed\" style=\"max-width: 605px; min-width: 325px;\" cite=\"https:\/\/www.tiktok.com\/@leagallo_\/video\/7365211800364797227\" data-video-id=\"7365211800364797227\">\n<section><a title=\"@leagallo_\" href=\"https:\/\/www.tiktok.com\/@leagallo_?refer=embed\" target=\"_blank\" rel=\"noopener\">@leagallo_<\/a> Les muestro un tipico MRE que es la comida milutar! <a title=\"military\" href=\"https:\/\/www.tiktok.com\/tag\/military?refer=embed\" target=\"_blank\" rel=\"noopener\">#military<\/a> <a title=\"army\" href=\"https:\/\/www.tiktok.com\/tag\/army?refer=embed\" target=\"_blank\" rel=\"noopener\">#army<\/a> <a title=\"vidamilitar\" href=\"https:\/\/www.tiktok.com\/tag\/vidamilitar?refer=embed\" target=\"_blank\" rel=\"noopener\">#vidamilitar<\/a> <a title=\"armylife\" href=\"https:\/\/www.tiktok.com\/tag\/armylife?refer=embed\" target=\"_blank\" rel=\"noopener\">#armylife<\/a> <a title=\"leagallo\" href=\"https:\/\/www.tiktok.com\/tag\/leagallo?refer=embed\" target=\"_blank\" rel=\"noopener\">#leagallo<\/a> <a title=\"mre\" href=\"https:\/\/www.tiktok.com\/tag\/mre?refer=embed\" target=\"_blank\" rel=\"noopener\">#mre<\/a> <a title=\"militarytiktok\" href=\"https:\/\/www.tiktok.com\/tag\/militarytiktok?refer=embed\" target=\"_blank\" rel=\"noopener\">#militarytiktok<\/a> <a title=\"\u266c original sound - Lea Gallo\" href=\"https:\/\/www.tiktok.com\/music\/original-sound-7365211853607160622?refer=embed\" target=\"_blank\" rel=\"noopener\">\u266c original sound &#8211; Lea Gallo<\/a><\/section>\n<\/blockquote>\n<p><script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script><\/p>\n<p><span data-contrast=\"auto\">Una de las curiosidades que muestra Lea en este video que supera las 600 mil reproducciones, es que la comida se pone dentro de un paquete al cual se le debe poner una medida de agua. Una vez hecho esto, se introduce el cartucho con los macarrones con queso y estos se van a calentar como si estuviesen acabados de hacer.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Y es que, por primera vez, miles de personas en todo el mundo est\u00e1n conociendo interioridades del Army estadounidense, m\u00e1s all\u00e1 de las im\u00e1genes hollywoodescas de las pel\u00edculas de acci\u00f3n.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Lea Gallo muestra la vida real de un oficial del ej\u00e9rcito, con las limitaciones del d\u00eda a d\u00eda y tambi\u00e9n con momentos humanos y valiosos, que su p\u00fablico agradece y vive junto a ella.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">En otro de sus videos m\u00e1s virales, le pregunta a uno de sus compa\u00f1eros de Army si es cierto que los militares son infieles. A lo que el sargento le contesta que todos son muy fieles, empezando por \u00e9l mismo que trae la fidelidad en la sangre. <\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Entre los comentarios a esta publicaci\u00f3n, destaca el de una usuaria que asegura que los \u201cobligan\u201d a ser fieles pues, de descubrirse que no es as\u00ed, los pueden degradar e incluso castigar.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0 \u00a0<\/span><\/p>\n<blockquote class=\"tiktok-embed\" style=\"max-width: 605px; min-width: 325px;\" cite=\"https:\/\/www.tiktok.com\/@leagallo_\/video\/7393762511691975966\" data-video-id=\"7393762511691975966\">\n<section><a title=\"@leagallo_\" href=\"https:\/\/www.tiktok.com\/@leagallo_?refer=embed\" target=\"_blank\" rel=\"noopener\">@leagallo_<\/a> Le creemos a @El Pepe_jl seran los militares fieles? <a title=\"militares\" href=\"https:\/\/www.tiktok.com\/tag\/militares?refer=embed\" target=\"_blank\" rel=\"noopener\">#militares<\/a> <a title=\"armylifestyle\" href=\"https:\/\/www.tiktok.com\/tag\/armylifestyle?refer=embed\" target=\"_blank\" rel=\"noopener\">#armylifestyle<\/a> <a title=\"usarmy\" href=\"https:\/\/www.tiktok.com\/tag\/usarmy?refer=embed\" target=\"_blank\" rel=\"noopener\">#usarmy<\/a> <a title=\"soldierlife\" href=\"https:\/\/www.tiktok.com\/tag\/soldierlife?refer=embed\" target=\"_blank\" rel=\"noopener\">#soldierlife<\/a> <a title=\"\u266c original sound - Lea Gallo\" href=\"https:\/\/www.tiktok.com\/music\/original-sound-7393762472848558879?refer=embed\" target=\"_blank\" rel=\"noopener\">\u266c original sound &#8211; Lea Gallo<\/a><\/section>\n<\/blockquote>\n<p><script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script><\/p>\n<p><span data-contrast=\"auto\">En cada uno de sus videos la sargento Gallo se asegura de mostrar esa faceta divertida propia de los cubanos, algo que es bien recibido y entendido por su p\u00fablico, que comprende se trata de contenido para redes sociales.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Con m\u00e1s de 70 mil seguidores en TikTok y m\u00e1s de mil en Instagram, esta cubana comparte su vida entre ser mam\u00e1 de un ni\u00f1o y su carrera como oficial del ej\u00e9rcito norteamericano, demostrando que con perseverancia y trabajo todos los sue\u00f1os son posibles en este pa\u00eds.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lea Gallo se ha hecho viral en redes sociales, despu\u00e9s de que compartiera con miles de usuarios algunos \u201csecretos\u201d de<\/p>\n","protected":false},"author":33,"featured_media":90487,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[15634],"tags":[],"class_list":["post-90486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vivir-trabajar-usa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos<\/title>\n<meta name=\"description\" content=\"Lea Gallo se ha hecho viral en redes sociales, despu\u00e9s de que compartiera algunos \u201csecretos\u201d de su vida en el Army de Estados Unidos.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos\" \/>\n<meta property=\"og:description\" content=\"Lea Gallo se ha hecho viral en redes sociales, despu\u00e9s de que compartiera algunos \u201csecretos\u201d de su vida en el Army de Estados Unidos.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista DimeCuba\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/DimeCuba\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-20T15:34:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-26T15:57:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2024\/08\/Lea-Gallo-Collage-Dime-Cuba-e1724168184787.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1146\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anabarbara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dimecuba\" \/>\n<meta name=\"twitter:site\" content=\"@dimecuba\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anabarbara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/\"},\"author\":{\"name\":\"anabarbara\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#\\\/schema\\\/person\\\/c9170ad69b8f1747349109bcefe6ea61\"},\"headline\":\"Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos\",\"datePublished\":\"2024-08-20T15:34:47+00:00\",\"dateModified\":\"2024-08-26T15:57:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/\"},\"wordCount\":642,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Lea-Gallo-Collage-Dime-Cuba-e1724168184787.jpg\",\"articleSection\":[\"VIVIR EN ESTADOS UNIDOS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/\",\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/\",\"name\":\"Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Lea-Gallo-Collage-Dime-Cuba-e1724168184787.jpg\",\"datePublished\":\"2024-08-20T15:34:47+00:00\",\"dateModified\":\"2024-08-26T15:57:54+00:00\",\"description\":\"Lea Gallo se ha hecho viral en redes sociales, despu\u00e9s de que compartiera algunos \u201csecretos\u201d de su vida en el Army de Estados Unidos.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Lea-Gallo-Collage-Dime-Cuba-e1724168184787.jpg\",\"contentUrl\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Lea-Gallo-Collage-Dime-Cuba-e1724168184787.jpg\",\"width\":2048,\"height\":1146,\"caption\":\"Cubana se hace viral en TikTok al mostrar su vida en el army. (Collage: Dime Cuba)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias de Cuba\",\"item\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VIVIR EN ESTADOS UNIDOS\",\"item\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/vivir-trabajar-usa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/\",\"name\":\"Revista DimeCuba\",\"description\":\"\u00daltimas noticias y sucesos de Cuba\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#organization\",\"name\":\"DimeCuba\",\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Revista-DimeCuba-logo-sml-3.png\",\"contentUrl\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Revista-DimeCuba-logo-sml-3.png\",\"width\":201,\"height\":57,\"caption\":\"DimeCuba\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/DimeCuba\\\/\",\"https:\\\/\\\/x.com\\\/dimecuba\",\"https:\\\/\\\/www.instagram.com\\\/dimecuba\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dimecuba\",\"https:\\\/\\\/www.youtube.com\\\/dimecubaweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/#\\\/schema\\\/person\\\/c9170ad69b8f1747349109bcefe6ea61\",\"name\":\"anabarbara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2068d959b6344abe419e9380ad193d5c007cf3d0e838d4a0fccea732b04b99e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2068d959b6344abe419e9380ad193d5c007cf3d0e838d4a0fccea732b04b99e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2068d959b6344abe419e9380ad193d5c007cf3d0e838d4a0fccea732b04b99e?s=96&d=mm&r=g\",\"caption\":\"anabarbara\"},\"url\":\"https:\\\/\\\/www.dimecuba.com\\\/revista\\\/author\\\/anabarbara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos","description":"Lea Gallo se ha hecho viral en redes sociales, despu\u00e9s de que compartiera algunos \u201csecretos\u201d de su vida en el Army de Estados Unidos.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/","og_locale":"es_ES","og_type":"article","og_title":"Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos","og_description":"Lea Gallo se ha hecho viral en redes sociales, despu\u00e9s de que compartiera algunos \u201csecretos\u201d de su vida en el Army de Estados Unidos.\u00a0","og_url":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/","og_site_name":"Revista DimeCuba","article_publisher":"https:\/\/facebook.com\/DimeCuba\/","article_published_time":"2024-08-20T15:34:47+00:00","article_modified_time":"2024-08-26T15:57:54+00:00","og_image":[{"width":2048,"height":1146,"url":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2024\/08\/Lea-Gallo-Collage-Dime-Cuba-e1724168184787.jpg","type":"image\/jpeg"}],"author":"anabarbara","twitter_card":"summary_large_image","twitter_creator":"@dimecuba","twitter_site":"@dimecuba","twitter_misc":{"Escrito por":"anabarbara","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/#article","isPartOf":{"@id":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/"},"author":{"name":"anabarbara","@id":"https:\/\/www.dimecuba.com\/revista\/#\/schema\/person\/c9170ad69b8f1747349109bcefe6ea61"},"headline":"Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos","datePublished":"2024-08-20T15:34:47+00:00","dateModified":"2024-08-26T15:57:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/"},"wordCount":642,"commentCount":0,"publisher":{"@id":"https:\/\/www.dimecuba.com\/revista\/#organization"},"image":{"@id":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2024\/08\/Lea-Gallo-Collage-Dime-Cuba-e1724168184787.jpg","articleSection":["VIVIR EN ESTADOS UNIDOS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/","url":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/","name":"Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos","isPartOf":{"@id":"https:\/\/www.dimecuba.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/#primaryimage"},"image":{"@id":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2024\/08\/Lea-Gallo-Collage-Dime-Cuba-e1724168184787.jpg","datePublished":"2024-08-20T15:34:47+00:00","dateModified":"2024-08-26T15:57:54+00:00","description":"Lea Gallo se ha hecho viral en redes sociales, despu\u00e9s de que compartiera algunos \u201csecretos\u201d de su vida en el Army de Estados Unidos.\u00a0","breadcrumb":{"@id":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/#primaryimage","url":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2024\/08\/Lea-Gallo-Collage-Dime-Cuba-e1724168184787.jpg","contentUrl":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2024\/08\/Lea-Gallo-Collage-Dime-Cuba-e1724168184787.jpg","width":2048,"height":1146,"caption":"Cubana se hace viral en TikTok al mostrar su vida en el army. (Collage: Dime Cuba)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/cubana-se-hace-viral-en-tiktok-al-revelar-secretos-del-army-de-estados-unidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias de Cuba","item":"https:\/\/www.dimecuba.com\/revista\/"},{"@type":"ListItem","position":2,"name":"VIVIR EN ESTADOS UNIDOS","item":"https:\/\/www.dimecuba.com\/revista\/vivir-trabajar-usa\/"},{"@type":"ListItem","position":3,"name":"Cubana se hace viral en TikTok al revelar \u201csecretos\u201d del Army de Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/www.dimecuba.com\/revista\/#website","url":"https:\/\/www.dimecuba.com\/revista\/","name":"Revista DimeCuba","description":"\u00daltimas noticias y sucesos de Cuba","publisher":{"@id":"https:\/\/www.dimecuba.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dimecuba.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.dimecuba.com\/revista\/#organization","name":"DimeCuba","url":"https:\/\/www.dimecuba.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.dimecuba.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2018\/10\/Revista-DimeCuba-logo-sml-3.png","contentUrl":"https:\/\/www.dimecuba.com\/revista\/wp-content\/uploads\/2018\/10\/Revista-DimeCuba-logo-sml-3.png","width":201,"height":57,"caption":"DimeCuba"},"image":{"@id":"https:\/\/www.dimecuba.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/DimeCuba\/","https:\/\/x.com\/dimecuba","https:\/\/www.instagram.com\/dimecuba\/","https:\/\/www.linkedin.com\/company\/dimecuba","https:\/\/www.youtube.com\/dimecubaweb"]},{"@type":"Person","@id":"https:\/\/www.dimecuba.com\/revista\/#\/schema\/person\/c9170ad69b8f1747349109bcefe6ea61","name":"anabarbara","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b2068d959b6344abe419e9380ad193d5c007cf3d0e838d4a0fccea732b04b99e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b2068d959b6344abe419e9380ad193d5c007cf3d0e838d4a0fccea732b04b99e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b2068d959b6344abe419e9380ad193d5c007cf3d0e838d4a0fccea732b04b99e?s=96&d=mm&r=g","caption":"anabarbara"},"url":"https:\/\/www.dimecuba.com\/revista\/author\/anabarbara\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/posts\/90486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/comments?post=90486"}],"version-history":[{"count":0,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/posts\/90486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/media\/90487"}],"wp:attachment":[{"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/media?parent=90486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/categories?post=90486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dimecuba.com\/revista\/wp-json\/wp\/v2\/tags?post=90486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}